{"id":2391,"date":"2022-12-19T07:44:57","date_gmt":"2022-12-19T05:44:57","guid":{"rendered":"https:\/\/www.rodon-hotel.gr\/travel-helper\/"},"modified":"2026-08-31T11:58:54","modified_gmt":"2026-08-31T08:58:54","slug":"assistenza-di-viaggio","status":"publish","type":"page","link":"https:\/\/www.rodon-hotel.gr\/it\/assistenza-di-viaggio\/","title":{"rendered":"Assistenza di viaggio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2391\" class=\"elementor elementor-2391 elementor-871\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a156877 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a156877\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-09c9353\" data-id=\"09c9353\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd76770 map-location elementor-widget elementor-widget-html\" data-id=\"cd76770\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<a href=\"#!\" onclick=\"fromYourLocation()\">Dalla tua posizione<\/a>\n<a href=\"#!\" onclick=\"initMap(35.540328192421704, 24.13043975830078,'35.513145275168284, 24.046279060820165')\">Dall'aeroporto di Chania<\/a>\n<a href=\"#!\" onclick=\"initMap(35.48936300690188, 24.076838493347168,'35.513145275168284, 24.046279060820165')\">Dal porto di Souda<\/a>\n<a href=\"#!\" onclick=\"initMap(35.33601110658638, 25.17414110577397,'35.513145275168284, 24.046279060820165')\">Dall'aeroporto di Heraklion<\/a>\n<a href=\"#!\" onclick=\"initMap(35.343507, 25.150937,'35.513145275168284, 24.046279060820165')\">Dal porto di Heraklion<\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ac6532 trvlHelper elementor-widget elementor-widget-html\" data-id=\"7ac6532\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"map\" style=\"width: 100%; height: 550px; float: left;\"><\/div> \n<div id=\"panel\" style=\"width: 100%; float: right;\"><\/div> \n\n <script src=\"https:\/\/maps.google.com\/maps\/api\/js?key=AIzaSyAdl-1diJgY7gF35lwi7Tkq8hrRKlQ3OPA&language=en\"><\/script>\n<script type=\"text\/javascript\"> \n  var directionsService = new google.maps.DirectionsService();\n    var destinationCords = '35.513145275168284, 24.046279060820165';\n  \n  function fromYourLocation() {\n    if (location.protocol == 'https:'){\n      if (navigator.geolocation) {\n        navigator.geolocation.getCurrentPosition(function (position) {                                                              \n          initMap(position.coords.latitude,position.coords.longitude,destinationCords)\n        });\n      }\n    }\n  }\n\n  initMap();\n  \n  function initMap(lat,long,destinationCordss){\n    if (lat && long && destinationCordss) {\n      originx = lat+','+long;\n      destinx = destinationCordss;\n    } else{\n      originx = '35.51379308593382,24.020161009539834';\n      destinx = destinationCords;\n    }\n    document.getElementById('panel').innerHTML = \"\"\n    var directionsDisplay = new google.maps.DirectionsRenderer({\n      draggable: true,\n      map: map,\n      panel: document.getElementById('panel')\n    });\n    var map = new google.maps.Map(document.getElementById('map'), {\n      zoom:7,\n      scrollwheel: false,\n      draggable: true,\n      mapTypeId: google.maps.MapTypeId.ROADMAP,\n      styles: [\n    \n    {\n        \"featureType\": \"all\",\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"saturation\": 36\n            },\n            {\n                \"color\": \"#333333\"\n            },\n            {\n                \"lightness\": 40\n            }\n        ]\n    },\n    {\n        \"featureType\": \"all\",\n        \"elementType\": \"labels.text.stroke\",\n        \"stylers\": [\n            {\n                \"visibility\": \"on\"\n            },\n            {\n                \"color\": \"#ffffff\"\n            },\n            {\n                \"lightness\": 16\n            }\n        ]\n    },\n    {\n        \"featureType\": \"all\",\n        \"elementType\": \"labels.icon\",\n        \"stylers\": [\n            {\n                \"visibility\": \"off\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"administrative\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#fefefe\"\n            },\n            {\n                \"lightness\": 20\n            }\n        ]\n    },\n    {\n        \"featureType\": \"administrative\",\n        \"elementType\": \"geometry.stroke\",\n        \"stylers\": [\n            {\n                \"color\": \"#fefefe\"\n            },\n            {\n                \"lightness\": 17\n            },\n            {\n                \"weight\": 1.2\n            }\n        ]\n    },\n    {\n        \"featureType\": \"landscape\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#f5f5f5\"\n            },\n            {\n                \"lightness\": 20\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#f5f5f5\"\n            },\n            {\n                \"lightness\": 21\n            },\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi.attraction\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi.attraction\",\n        \"elementType\": \"labels.text\",\n        \"stylers\": [\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi.government\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi.government\",\n        \"elementType\": \"labels.text\",\n        \"stylers\": [\n            {\n                \"visibility\": \"off\"\n            },\n            {\n                \"color\": \"#717171\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi.park\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#dedede\"\n            },\n            {\n                \"lightness\": 21\n            },\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.highway\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#888888\"\n            },\n            {\n                \"lightness\": 17\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.highway\",\n        \"elementType\": \"geometry.stroke\",\n        \"stylers\": [\n            {\n                \"color\": \"#801818\"\n            },\n            {\n                \"lightness\": 29\n            },\n            {\n                \"weight\": 0.2\n            },\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.arterial\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#4d6dae\"\n            },\n            {\n                \"lightness\": 18\n            },\n            {\n                \"weight\": \"0.97\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.local\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#717171\"\n            },\n            {\n                \"lightness\": 16\n            },\n            {\n                \"gamma\": \"1.16\"\n            },\n            {\n                \"weight\": \"0.49\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"transit\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#F3EEE7\"\n            },\n            {\n                \"lightness\": 19\n            }\n        ]\n    },\n    {\n        \"featureType\": \"water\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#F3EEE7\"\n            },\n            {\n                \"lightness\": 17\n            }\n        ]\n    }\n\n]\n    });\n    directionsDisplay.setMap(map);\n    directionsDisplay.setPanel(document.getElementById('panel'));\n    var request = {\n      origin: originx,\n      destination: destinx,\n      travelMode: google.maps.DirectionsTravelMode.DRIVING\n    };\n    directionsService.route(request, function(response, status) {\n      if (status == google.maps.DirectionsStatus.OK) {\n        directionsDisplay.setDirections(response);\n      }\n    });\n  }\n<\/script>  \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dalla tua posizione Dall&#8217;aeroporto di Chania Dal porto di Souda Dall&#8217;aeroporto di Heraklion Dal porto di Heraklion<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-2391","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.rodon-hotel.gr\/it\/wp-json\/wp\/v2\/pages\/2391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rodon-hotel.gr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rodon-hotel.gr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rodon-hotel.gr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rodon-hotel.gr\/it\/wp-json\/wp\/v2\/comments?post=2391"}],"version-history":[{"count":4,"href":"https:\/\/www.rodon-hotel.gr\/it\/wp-json\/wp\/v2\/pages\/2391\/revisions"}],"predecessor-version":[{"id":2395,"href":"https:\/\/www.rodon-hotel.gr\/it\/wp-json\/wp\/v2\/pages\/2391\/revisions\/2395"}],"wp:attachment":[{"href":"https:\/\/www.rodon-hotel.gr\/it\/wp-json\/wp\/v2\/media?parent=2391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}